{"id":27,"count":4,"description":"","link":"https:\/\/eclatperfumes.com\/ar\/tag\/chypre\/","name":"\u0634\u064a\u0628\u0631","slug":"chypre","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/eclatperfumes.com\/ar\/wp-json\/wp\/v2\/tags\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eclatperfumes.com\/ar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eclatperfumes.com\/ar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eclatperfumes.com\/ar\/wp-json\/wp\/v2\/posts?tags=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}